{"id":4506154,"date":"2026-01-19T17:25:58","date_gmt":"2026-01-19T22:25:58","guid":{"rendered":"https:\/\/prideatwork.ca\/?post_type=tribe_events&#038;p=4506154"},"modified":"2026-01-19T17:25:58","modified_gmt":"2026-01-19T22:25:58","slug":"matrices-20260324","status":"publish","type":"tribe_events","link":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/","title":{"rendered":"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3972935 size-full\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3.png\" alt=\"\" width=\"960\" height=\"574\" srcset=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3.png 960w, https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3-450x269.png 450w, https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3-750x448.png 750w\" sizes=\"auto, (max-width: 180px) 180px, (max-width: 450px) 450px, (max-width: 750px) 750px, (max-width: 1170px) 1170px, (max-width: 1440px) 1440px, (max-width: 1920px) 1920px, 960px\" \/><\/p>\n<p><strong>Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres est un \u00e9v\u00e9nement de r\u00e9seautage num\u00e9rique gratuit<\/strong> pour les personnes trans, non binaires et agenres en emploi et en recherche d\u2019emploi partout au Canada.<\/p>\n<p>Depuis son lancement en 2020, ce programme permanent a permis de cr\u00e9er des espaces plus s\u00fbrs et intentionnels o\u00f9 les participant\u00b7es peuvent partager leurs histoires, \u00e9tablir des liens professionnels et favoriser la cr\u00e9ation d&#8217;une communaut\u00e9 dans un contexte num\u00e9rique. Chaque ann\u00e9e, le programme poursuit sur la lanc\u00e9e des rencontres pr\u00e9c\u00e9dentes afin de renforcer les r\u00e9seaux et d&#8217;amplifier les voix des communaut\u00e9s trans, non binaires et agenres.<\/p>\n<p><strong>Format<\/strong> : cette rencontre se compose de deux tours de discussions th\u00e9matiques, sous forme de tables rondes. Au cours de chaque tour, les participant\u00b7es se joignent \u00e0 un petit groupe anim\u00e9 pour approfondir un sujet sp\u00e9cifique en rapport avec le th\u00e8me de la rencontre.<\/p>\n<h4>Pourquoi cet \u00e9v\u00e9nement a-t-il lieu?<\/h4>\n<p>Bien que de nombreux espaces de r\u00e9seautage soient ouverts aux personnes trans, non binaires et agenres, ces communaut\u00e9s font face \u00e0 des exp\u00e9riences, des questions et des d\u00e9fis distincts dans le cadre professionnel.<\/p>\n<p>Cet \u00e9v\u00e9nement a \u00e9t\u00e9 cr\u00e9\u00e9 pour :<\/p>\n<ul>\n<li>Offrir un soutien par les pairs qui englobe diff\u00e9rentes identit\u00e9s et r\u00e9gions g\u00e9ographiques.<\/li>\n<li>Favoriser la cr\u00e9ation de liens par le partage d&#8217;exp\u00e9riences v\u00e9cues communes.<\/li>\n<li>R\u00e9pondre directement aux commentaires des membres de la communaut\u00e9 et des participant\u00b7es.<\/li>\n<\/ul>\n<h4>Public cible :<\/h4>\n<p>Cet \u00e9v\u00e9nement est <em>destin\u00e9<\/em> aux personnes qui s\u2019identifient comme <strong>trans<\/strong>, <strong>non binaires<\/strong> ou <strong>agenres<\/strong>.<\/p>\n<p><strong>Il n&#8217;est pas n\u00e9cessaire de \u00ab prouver \u00bb son identit\u00e9<\/strong> ou de r\u00e9pondre \u00e0 des crit\u00e8res autres que l&#8217;auto-identification. Bien que nous reconnaissions l&#8217;importance de l&#8217;alliance inclusive et des personnes alli\u00e9es, cet espace est volontairement r\u00e9serv\u00e9 aux personnes trans, non binaires et agenres pour qu&#8217;elles puissent \u00e9changer en toute libert\u00e9. Les personnes alli\u00e9es sont encourag\u00e9es \u00e0 respecter les limites des espaces centr\u00e9s sur l&#8217;identit\u00e9 et \u00e0 laisser la place en se retirant et en s&#8217;engageant plut\u00f4t dans nos programmes \u00e9ducatifs ou d&#8217;autres programmes de r\u00e9seautage.<\/p>\n<h4>Objectifs cl\u00e9s :<\/h4>\n<ul>\n<li>Cr\u00e9er des liens avec d&#8217;autres personnes ayant des parcours professionnels similaires.<\/li>\n<li>Partager des exp\u00e9riences v\u00e9cues dans un espace soutenant et affirmant.<\/li>\n<li>B\u00e2tir une communaut\u00e9 et \u00e9largir son r\u00e9seau.<\/li>\n<li>Se renseigner sur les initiatives et \u00e9v\u00e9nements de Fiert\u00e9 au travail Canada \u00e0 venir.<\/li>\n<\/ul>\n<h4>Accessibilit\u00e9 :<\/h4>\n<ul>\n<li>Langue parl\u00e9e : Anglais<\/li>\n<li>Sous-titrage : Anglais<\/li>\n<li>Format : Virtuel (Zoom en mode rencontre)<\/li>\n<li>Type de participation : Les personnes participantes sont invit\u00e9es \u00e0 \u00e9changer par vid\u00e9o, audio ou clavardage.<\/li>\n<\/ul>\n<strong>Registration for this event has closed.<\/strong>\n<p>Pour toute autre demande d&#8217;accessibilit\u00e9, veuillez l&#8217;indiquer dans votre formulaire d&#8217;inscription ou communiquez avec nous \u00e0 : <a href=\"mailto:events@prideatwork.ca\">events@prideatwork.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres est un \u00e9v\u00e9nement de r\u00e9seautage num\u00e9rique gratuit pour les personnes trans, non binaires et agenres en emploi et en recherche d\u2019emploi partout au Canada. Depuis son lancement en 2020, ce programme permanent a permis de cr\u00e9er des espaces plus s\u00fbrs et intentionnels o\u00f9 les participant\u00b7es peuvent partager leurs histoires, \u00e9tablir des liens professionnels et favoriser la cr\u00e9ation d&#8217;une communaut\u00e9 dans un contexte num\u00e9rique. Chaque [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[35],"class_list":["post-4506154","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-networking-fr","cat_networking-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres - Pride At Work Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres - Pride At Work Canada\" \/>\n<meta property=\"og:description\" content=\"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres est un \u00e9v\u00e9nement de r\u00e9seautage num\u00e9rique gratuit pour les personnes trans, non binaires et agenres en emploi et en recherche d\u2019emploi partout au Canada. Depuis son lancement en 2020, ce programme permanent a permis de cr\u00e9er des espaces plus s\u00fbrs et intentionnels o\u00f9 les participant\u00b7es peuvent partager leurs histoires, \u00e9tablir des liens professionnels et favoriser la cr\u00e9ation d&#8217;une communaut\u00e9 dans un contexte num\u00e9rique. Chaque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/\" \/>\n<meta property=\"og:site_name\" content=\"Pride At Work Canada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"574\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/\",\"name\":\"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres - Pride At Work Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2300_Matrice_Chalk_Banner_640x200-3.png\",\"datePublished\":\"2026-01-19T22:25:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2300_Matrice_Chalk_Banner_640x200-3.png\",\"contentUrl\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2300_Matrice_Chalk_Banner_640x200-3.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/matrices-20260324\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/\",\"name\":\"Pride At Work Canada\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prideatwork.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres - Pride At Work Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/","og_locale":"fr_FR","og_type":"article","og_title":"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres - Pride At Work Canada","og_description":"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres est un \u00e9v\u00e9nement de r\u00e9seautage num\u00e9rique gratuit pour les personnes trans, non binaires et agenres en emploi et en recherche d\u2019emploi partout au Canada. Depuis son lancement en 2020, ce programme permanent a permis de cr\u00e9er des espaces plus s\u00fbrs et intentionnels o\u00f9 les participant\u00b7es peuvent partager leurs histoires, \u00e9tablir des liens professionnels et favoriser la cr\u00e9ation d&#8217;une communaut\u00e9 dans un contexte num\u00e9rique. Chaque [&hellip;]","og_url":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/","og_site_name":"Pride At Work Canada","og_image":[{"width":960,"height":574,"url":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/","url":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/","name":"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres - Pride At Work Canada","isPartOf":{"@id":"https:\/\/prideatwork.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/#primaryimage"},"image":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/#primaryimage"},"thumbnailUrl":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3.png","datePublished":"2026-01-19T22:25:58+00:00","breadcrumb":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/#primaryimage","url":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3.png","contentUrl":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/03\/2300_Matrice_Chalk_Banner_640x200-3.png"},{"@type":"BreadcrumbList","@id":"https:\/\/prideatwork.ca\/fr\/event\/matrices-20260324\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prideatwork.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/prideatwork.ca\/fr\/events\/"},{"@type":"ListItem","position":3,"name":"Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres"}]},{"@type":"WebSite","@id":"https:\/\/prideatwork.ca\/#website","url":"https:\/\/prideatwork.ca\/","name":"Pride At Work Canada","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prideatwork.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/4506154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/users\/28"}],"version-history":[{"count":1,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/4506154\/revisions"}],"predecessor-version":[{"id":4506155,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/4506154\/revisions\/4506155"}],"wp:attachment":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/media?parent=4506154"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tags?post=4506154"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=4506154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}