{"id":4069021,"date":"2023-09-21T11:09:27","date_gmt":"2023-09-21T15:09:27","guid":{"rendered":"https:\/\/prideatwork.ca\/?post_type=tribe_events&#038;p=4069021"},"modified":"2023-11-01T13:43:59","modified_gmt":"2023-11-01T17:43:59","slug":"webinar-20231122","status":"publish","type":"tribe_events","link":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/","title":{"rendered":"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires &#8211; fran\u00e7ais]"},"content":{"rendered":"<p><strong>Le mercredi 22 novembre 2023 de 12 h \u00e0 13 h HNE &#8211; cet \u00e9v\u00e9nement est offert en exclusivit\u00e9 au personnel de nos organisations <a href=\"https:\/\/prideatwork.ca\/fr\/a-propos\/fieres-partenaires\/\" target=\"_blank\" rel=\"noopener\">Fi\u00e8res partenaires<\/a> et <a href=\"https:\/\/prideatwork.ca\/fr\/a-propos\/partenaires-communautaires\/\" target=\"_blank\" rel=\"noopener\">Partenaires communautaires<\/a>. Cette session sera <a href=\"https:\/\/prideatwork.ca\/fr\/event\/workshop-20230823\/\" target=\"_blank\" rel=\"noopener noreferrer\">offerte en anglais le 23 ao\u00fbt<\/a>.<\/strong><br \/>\nUn sous-titrage en direct sera assur\u00e9 par 3 Play Media Canada.<\/p>\n<p>Plongez au c\u0153ur de la Semaine de sensibilisation aux personnes trans et la Journ\u00e9e du souvenir transgenre le 20 novembre en participant \u00e0 un webinaire captivant : \u00ab Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases \u00bb. Pr\u00e9sent\u00e9 avec Fiert\u00e9 au Travail Canada, cet \u00e9v\u00e9nement va bien plus loin en explorant des strat\u00e9gies avanc\u00e9es pour favoriser une inclusion transformatrice au sein du milieu professionnel. Nous mettrons en lumi\u00e8re des mesures concr\u00e8tes qui renforcent l&#8217;\u00e9quit\u00e9 et l&#8217;accessibilit\u00e9 pour toustes.<\/p>\n<p>De plus, nous aurons le plaisir d&#8217;\u00eatre accompagn\u00e9.e.s par <a href=\"https:\/\/celeste.lgbt\/fr\/\" rel=\"noopener\" target=\"_blank\">C\u00e9leste Trianon<\/a>, une juriste transf\u00e9minine et militante r\u00e9solument engag\u00e9e, \u0153uvrant sur les terres traditionnelles non c\u00e9d\u00e9es des Kanien\u2019keh\u00e1:ka. Son travail percutant vise \u00e0 briser les barri\u00e8res administratives et juridiques auxquelles sont confront\u00e9es quotidiennement les personnes trans. C\u00e9leste est \u00e9galement l\u2019organisatrice de la marche de la Fiert\u00e9 trans \u00e0 Montr\u00e9al.<\/p>\n<p>Pr\u00e9parez-vous \u00e0 une exploration inspirante de strat\u00e9gies transformatrices en mati\u00e8re d&#8217;inclusion, plongeant en profondeur pour cr\u00e9er des environnements de travail qui non seulement acceptent, mais aussi renforcent v\u00e9ritablement. Ne manquez pas cette opportunit\u00e9 exceptionnelle d&#8217;apprentissage et de d\u00e9veloppement.<\/p>\n<p><strong>Objectifs d\u2019apprentissage :<\/strong><\/p>\n<ul>\n<li>Comprendre les m\u00e9thodes de recrutement et de promotion sp\u00e9cifiques aux personnes transgenres, afin de d\u00e9velopper des strat\u00e9gies efficaces pour embaucher et faire progresser ces individus au sein de l&#8217;organisation.<\/li>\n<li>Examiner l&#8217;intersectionnalit\u00e9 dans le contexte des personnes transgenres, en analysant les croisements entre diff\u00e9rents aspects de leur identit\u00e9, et en \u00e9valuant comment ces facteurs influencent leurs exp\u00e9riences et leurs besoins.<\/li>\n<li>Explorer les pratiques optimales pour la r\u00e9tention et l&#8217;inclusion des personnes transgenres en milieu professionnel, en explorant des exemples concrets et en d\u00e9veloppant des comp\u00e9tences pour cr\u00e9er un environnement accueillant et \u00e9quitable.<\/li>\n<\/ul>\n<p><strong>Public :<\/strong><\/p>\n<ul>\n<li>Tous.te.s les employ\u00e9.e.s<\/li>\n<li>Professionnel.le.s de la diversit\u00e9, de l&#8217;\u00e9quit\u00e9 et de l&#8217;inclusion<\/li>\n<li>Professionnel.le.s en ressources humaines<\/li>\n<\/ul>\n<h6>Pr\u00e9sentation donn\u00e9e par :<\/h6>\n<p>[vc_row][vc_column width=&#8221;1\/4&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-239151\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/09\/Celeste-Trianon.jpg\" width=\"200\" height=\"200\" \/>[\/vc_column][vc_column width=&#8221;3\/4&#8243;]<strong>C\u00e9leste Trianon (elle\/la), Directrice ex\u00e9cutive, Trans Legal Collective<\/strong><\/p>\n<p>C\u00e9leste Trianon, un nom qui r\u00e9sonne avec puissance et engagement. En tant que juriste et militante transf\u00e9minine, elle s&#8217;engage sur les terres traditionnelles des Kanien\u2019keh\u00e1:ka, qui n&#8217;ont jamais \u00e9t\u00e9 c\u00e9d\u00e9es. Sa mission est claire : briser les barri\u00e8res administratives et juridiques qui entravent le quotidien des personnes trans. Mais elle va au-del\u00e0, elle cultive la joie de vivre et c\u00e9l\u00e8bre la diversit\u00e9 des identit\u00e9s de genre et des formes d&#8217;expression queer.<\/p>\n<p>Du haut de ses 19 ans, C\u00e9leste Trianon se distingue comme cheffe de file des manifestations de protestation. \u00c9tudiante en droit \u00e0 l&#8217;Universit\u00e9 de Montr\u00e9al, elle incarne la force du changement en tant que coordinatrice de la <a href=\"https:\/\/celeste.lgbt\/fr\/transition-legale\/clinique\/\" rel=\"noopener\" target=\"_blank\">Clinique de transition l\u00e9gale<\/a> du Qu\u00e9bec. Elle n&#8217;a pas peur de se battre, comme en t\u00e9moigne son r\u00f4le essentiel dans l&#8217;organisation de protestations contre le Projet de loi 2 au Qu\u00e9bec, un combat pour la reconnaissance et les droits des personnes trans. Elle a \u00e9galement cr\u00e9\u00e9 <a href=\"https:\/\/celeste.lgbt\/fr\/transition-legale\/kb\/\" rel=\"noopener\" target=\"_blank\">Transitionne-moi<\/a>, une ressource d\u00e9velopp\u00e9e pour d\u00e9mystifier et expliquer la transition l\u00e9gale en contexte qu\u00e9b\u00e9cois ainsi que canadien pour les personnes trans naviguant les m\u00e9andres du processus de transition l\u00e9gale dans la province du Qu\u00e9bec. Depuis ao\u00fbt 2022, elle organise la Marche pour la Lib\u00e9ration et la Fiert\u00e9 Trans pendant la Semaine de la Fiert\u00e9.<\/p>\n<p>C\u00e9leste Trianon incarne la d\u00e9termination in\u00e9branlable et l&#8217;engagement profond pour les droits des personnes trans. Elle rayonne, elle inspire et elle ouvre la voie vers un avenir plus inclusif et \u00e9clair\u00e9 pour tous.te.s.<br \/>\n[\/vc_column][\/vc_row]<\/p>\n<p><strong>Accessibilit\u00e9 :<\/strong><\/p>\n<ul>\n<li>Langue parl\u00e9e : fran\u00e7ais<\/li>\n<li>Sous-titrage en direct en fran\u00e7ais et traduction automatique en anglais fournis par 3Play Media Canada.<\/li>\n<li>Format : Virtuel (sur Zoom)<\/li>\n<li>Type d&#8217;engagement : les participant.e.s sont invit\u00e9.e.s \u00e0 s\u2019exprimer dans le chat.<\/li>\n<li>La pr\u00e9sentation PowerPoint sera disponible avant la session pour les personnes ayant des besoins d&#8217;accessibilit\u00e9.<\/li>\n<li>Veuillez vous inscrire ci-dessous pour toute demande d&#8217;accessibilit\u00e9 suppl\u00e9mentaire. Toutes les questions peuvent \u00eatre envoy\u00e9es \u00e0 <a href=\"mailto:info@prideatwork.ca\" target=\"_blank\" rel=\"noopener\">info@prideatwork.ca<\/a>.<\/li>\n<\/ul>\n<strong>Registration for this event has closed.<\/strong>\n<p>Cet \u00e9v\u00e9nement est exclusif aux employ\u00e9s de nos organisations <a href=\"https:\/\/prideatwork.ca\/fr\/a-propos\/fieres-partenaires\/\" target=\"_blank\" rel=\"noopener\">Fi\u00e8res partenaires<\/a> et <a href=\"https:\/\/prideatwork.ca\/fr\/a-propos\/partenaires-communautaires\/\" target=\"_blank\" rel=\"noopener\">Partenaires communautaires<\/a>. Si vous souhaitez vous inscrire apr\u00e8s la date limite, s\u2019il vous pla\u00eet envoyez un courriel \u00e0 <a href=\"mailto:info@prideatwork.ca\" target=\"_blank\" rel=\"noopener\">info@prideatwork.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mercredi 22 novembre 2023 de 12 h \u00e0 13 h HNE &#8211; cet \u00e9v\u00e9nement est offert en exclusivit\u00e9 au personnel de nos organisations Fi\u00e8res partenaires et Partenaires communautaires. Cette session sera offerte en anglais le 23 ao\u00fbt. Un sous-titrage en direct sera assur\u00e9 par 3 Play Media Canada. Plongez au c\u0153ur de la Semaine de sensibilisation aux personnes trans et la Journ\u00e9e du souvenir transgenre le 20 novembre en participant \u00e0 un webinaire captivant [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[32],"class_list":["post-4069021","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-webinar-fr","cat_webinar-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais] - Pride At Work Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais]\" \/>\n<meta property=\"og:description\" content=\"Le mercredi 22 novembre 2023 de 12 h \u00e0 13 h HNE &#8211; cet \u00e9v\u00e9nement est offert en exclusivit\u00e9 au personnel de nos organisations Fi\u00e8res partenaires et Partenaires communautaires. Cette session sera offerte en anglais le 23 ao\u00fbt. Un sous-titrage en direct sera assur\u00e9 par 3 Play Media Canada. Plongez au c\u0153ur de la Semaine de sensibilisation aux personnes trans et la Journ\u00e9e du souvenir transgenre le 20 novembre en participant \u00e0 un webinaire captivant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/\" \/>\n<meta property=\"og:site_name\" content=\"Pride At Work Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-01T17:43:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/10\/Nov-22-Thumbnail-FR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/10\/Nov-22-Thumbnail-FR.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/\",\"name\":\"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais] - Pride At Work Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Celeste-Trianon.jpg\",\"datePublished\":\"2023-09-21T15:09:27+00:00\",\"dateModified\":\"2023-11-01T17:43:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Celeste-Trianon.jpg\",\"contentUrl\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Celeste-Trianon.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/webinar-20231122\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires &#8211; fran\u00e7ais]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/\",\"name\":\"Pride At Work Canada\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prideatwork.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais] - Pride At Work Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/","og_locale":"fr_FR","og_type":"article","og_title":"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais]","og_description":"Le mercredi 22 novembre 2023 de 12 h \u00e0 13 h HNE &#8211; cet \u00e9v\u00e9nement est offert en exclusivit\u00e9 au personnel de nos organisations Fi\u00e8res partenaires et Partenaires communautaires. Cette session sera offerte en anglais le 23 ao\u00fbt. Un sous-titrage en direct sera assur\u00e9 par 3 Play Media Canada. Plongez au c\u0153ur de la Semaine de sensibilisation aux personnes trans et la Journ\u00e9e du souvenir transgenre le 20 novembre en participant \u00e0 un webinaire captivant [&hellip;]","og_url":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/","og_site_name":"Pride At Work Canada","article_modified_time":"2023-11-01T17:43:59+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/10\/Nov-22-Thumbnail-FR.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais]","twitter_image":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/10\/Nov-22-Thumbnail-FR.png","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/","url":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/","name":"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires - fran\u00e7ais] - Pride At Work Canada","isPartOf":{"@id":"https:\/\/prideatwork.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/#primaryimage"},"image":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/#primaryimage"},"thumbnailUrl":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/09\/Celeste-Trianon.jpg","datePublished":"2023-09-21T15:09:27+00:00","dateModified":"2023-11-01T17:43:59+00:00","breadcrumb":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/#primaryimage","url":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/09\/Celeste-Trianon.jpg","contentUrl":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/09\/Celeste-Trianon.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/prideatwork.ca\/fr\/event\/webinar-20231122\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prideatwork.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/prideatwork.ca\/fr\/events\/"},{"@type":"ListItem","position":3,"name":"Webinaire : Inclusion des personnes trans en milieu professionnel : Aller au-del\u00e0 des bases [parternaires &#8211; fran\u00e7ais]"}]},{"@type":"WebSite","@id":"https:\/\/prideatwork.ca\/#website","url":"https:\/\/prideatwork.ca\/","name":"Pride At Work Canada","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prideatwork.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/4069021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":10,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/4069021\/revisions"}],"predecessor-version":[{"id":4103058,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/4069021\/revisions\/4103058"}],"wp:attachment":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/media?parent=4069021"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tags?post=4069021"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=4069021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}