{"id":3925613,"date":"2022-12-01T09:44:29","date_gmt":"2022-12-01T14:44:29","guid":{"rendered":"https:\/\/prideatwork.ca\/?post_type=tribe_events&#038;p=3925613"},"modified":"2023-01-25T15:21:09","modified_gmt":"2023-01-25T20:21:09","slug":"spark-20230210","status":"publish","type":"tribe_events","link":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/","title":{"rendered":"SPARK"},"content":{"rendered":"<p><em>(Veuillez noter que cet \u00e9v\u00e9nement est offert en anglais.)<\/em><\/p>\n<p><strong>Le vendredi 10 f\u00e9vrier 2023 de 8 h \u00e0 12 h HNE &#8211; Cet \u00e9v\u00e9nement payant porte sur le leadership et est ouvert \u00e0 toute personne int\u00e9ress\u00e9e. L\u2019\u00e9v\u00e9nement en anglais sera pr\u00e9sent\u00e9 en pr\u00e9sentiel et le nombre de participants est limit\u00e9.<\/strong><\/p>\n<p><center><img decoding=\"async\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/12\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg\" alt=\"Banni\u00e8re avec quelques formes g\u00e9om\u00e9triques et lignes en bas et les phrases Trouvez de l\u2019inspiration. Repartez avec une nouvelle perspective. Suscitez un vrai changement. avec l'\u00e9v\u00e9nement nom Spark\" \/><\/center><strong>SPARK<\/strong> est un \u00e9v\u00e9nement cr\u00e9atif\/d&#8217;affaires d\u2019une demie-journ\u00e9e qui met en relation des leaders en mati\u00e8re de diversit\u00e9, d\u2019\u00e9quit\u00e9 et d\u2019inclusion (DEI) avec des cadres sup\u00e9rieurs pour permettre un apprentissage partag\u00e9 ainsi que le r\u00e9seautage.<\/p>\n<p><center><\/p>\n<h4>Trouvez de l\u2019inspiration. Repartez avec une nouvelle perspective. Suscitez un vrai changement.<\/h4>\n<p><\/center><\/p>\n<p>Les participants auront droit en exclusivit\u00e9 \u00e0 une pr\u00e9sentation de Chris Bergeron (pronoms f\u00e9minins), auteure et vice-pr\u00e9sidente de la cr\u00e9ativit\u00e9 inclusive chez Cossette. Bergeron parlera de l\u2019exp\u00e9rience de perdre son privil\u00e8ge masculin en tant que femme transgenre. Le directeur g\u00e9n\u00e9ral de Fiert\u00e9 au travail Canada, Colin Druhan (pronoms masculins), fera le point sur une \u00e9tude r\u00e9cente qui se penche sur les exp\u00e9riences des communaut\u00e9s 2SLGBTQIA+ sur le march\u00e9 du travail au Canada.<\/p>\n<p>Par le biais d\u2019une exploration collaborative, les personnes participantes prendront part \u00e0 <strong>trois tables rondes<\/strong> explorant les intersections de l&#8217;inclusion des communaut\u00e9s 2SLGBTQIA+ avec <strong>la solidarit\u00e9 autochtone<\/strong>, <strong>le racisme anti-noir<\/strong> et <strong>l\u2019accessibilit\u00e9<\/strong>. Ces sessions seront codirig\u00e9es par des membres du personnel de Fiert\u00e9 au travail Canada et des leaders communautaires issus d\u2019un \u00e9ventail d\u2019exp\u00e9riences v\u00e9cues.<\/p>\n<p><strong>Pan\u00e9listes des tables rondes :<\/strong><\/p>\n<ul>\n<li><strong>La solidarit\u00e9 autochtone :<\/strong> Tim Geauvreau (il\/lui), Finances &amp; administration, Workforce Warriors, &amp; Londzo Drury (elle\/la), directrice de la culture &amp; du lieu de travail, Fiert\u00e9 au travail Canada<\/li>\n<li><strong>Le racisme anti-noir :<\/strong> Hildah Otieno Juma (elle\/la), directrice g\u00e9n\u00e9rale, Black Talent Initiative, &amp; Colin Druhan (il\/lui), directeur g\u00e9n\u00e9ral, Fiert\u00e9 au travail Canada<\/li>\n<li><strong>L\u2019accessibilit\u00e9 :<\/strong> Melissa Egan (elle\/la), chef des projets nationaux sur les Invalidit\u00e9s Episodiques, R\u00e9alise, &amp; Jade Pichette (elle\/la), directrice des programmes, Fiert\u00e9 au travail Canada<\/li>\n<\/ul>\n<h5 style=\"text-align: center;\">COMMANDITAIRE PRINCIPAL<\/h5>\n<p>[vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221;][vc_column width=&#8221;1\/1&#8243;][vc_column_text]<\/p>\n<p><center><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-48269\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/03\/PRIDE-SB-Corporate-Red-HEX-F.png\" alt=\"Scotiabank rainbow logo\" width=\"513\" height=\"87\" \/><\/center><br \/>\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<p><strong>Objectifs d\u2019apprentissage :<\/strong><\/p>\n<ul>\n<li>Comprendre l&#8217;intersectionnalit\u00e9 pr\u00e9sente dans les communaut\u00e9s 2SLGBTQIA+.<\/li>\n<li>D\u00e9velopper de nouvelles perspectives pour r\u00e9soudre les d\u00e9fis de la DEI.<\/li>\n<li>\u00c9tablir des liens avec des leaders de diff\u00e9rents secteurs d\u2019activit\u00e9.<\/li>\n<\/ul>\n<p><strong>Accr\u00e9ditation:<\/strong><\/p>\n<ul>\n<li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2021\/09\/accreditation-edi-fr.png\" alt=\"logo d\u2019agr\u00e9ment de EDetI du Barreau de l\u2019Ontario\" width=\"100\" height=\"100\" \/><strong>Barreau de l\u2019Ontario<\/strong> &#8211; Ce programme contient <strong>quatre (4) heures<\/strong> de contenu de professionnalisme sur l\u2019\u00e9galit\u00e9, la diversit\u00e9 et l\u2019inclusion.<\/li>\n<\/ul>\n<p><strong>Public cible :<\/strong><\/p>\n<ul>\n<li>Commanditaires principaux<\/li>\n<li>Sp\u00e9cialistes de la DEI<\/li>\n<li>Entrepreneurs et membres de la direction<\/li>\n<\/ul>\n<h5 style=\"text-align: center;\">LIEU ET COMMANDITAIRE H\u00d4TE<\/h5>\n<p>[vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221;][vc_column width=&#8221;2\/4&#8243;]<br \/>\n<strong>BLG &#8211; Borden Ladner Gervais<\/strong><br \/>\nBay Adelaide Centre, East Tower<br \/>\n22 Adelaide St W Suite 3400<br \/>\nToronto, ON M5H 4E3<br \/>\n[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<br \/>\n<img decoding=\"async\" class=\"wp-image-211727 alignleft\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/11\/BLG_Letters_Logo-scaled.jpg\" alt=\"\" width=\"\" height=\"\" \/><br \/>\n[\/vc_column][vc_column width=&#8221;1\/4&#8243;]<\/p>\n<p>[\/vc_column][\/vc_row]<\/p>\n<p><strong>Cette matin\u00e9e cr\u00e9ative de remue-m\u00e9ninges sera pr\u00e9c\u00e9d\u00e9e d\u2019un brunch d\u2019ouverture offert par la <a href=\"https:\/\/dispatchcoffee.ca\/fr-CA\" target=\"_blank\" rel=\"noopener\">Dispatch<\/a>, fond\u00e9 par des entrepreneur.e.s de nos communaut\u00e9s.<\/strong><\/p>\n<p><center><a href=\"https:\/\/dispatchcoffee.ca\/fr-CA\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-48269\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/01\/Dispatch_Logo.png\" alt=\"Dispatch logo\" width=\"155\" height=\"108\" \/><\/a><\/center><\/p>\n<h5 style=\"text-align: center;\">ENREGISTREMENT ET PRIX<\/h5>\n<p>PLACES LIMIT\u00c9ES ! Achetez vos billets d\u00e8s que possible. La proc\u00e9dure par laquelle les personnes int\u00e9ress\u00e9es \u00e0 participer sera ouverte du mardi 13 d\u00e9cembre 2022 au vendredi 3 f\u00e9vrier 2023 et les frais de participation sont de:<\/p>\n<ul>\n<li><strong>Billets g\u00e9n\u00e9raux :<\/strong><br \/>\n1 100 $ (plus les frais)<br \/>\nPour les haut.e.s dirigeant.e.s d\u2019autres entreprises &amp; organisations (non-partenaires).<\/li>\n<li><strong>Billets pour les partenaires :<\/strong><br \/>\n600 $ (plus les frais)<br \/>\nLes haut.e.s dirigeant.e.s des organisations <a href=\"https:\/\/prideatwork.ca\/fr\/a-propos\/fieres-partenaires\/\" target=\"_blank\" rel=\"noopener\"><strong>Fi\u00e8res partenaires<\/strong><\/a> &amp; <a href=\"https:\/\/prideatwork.ca\/fr\/a-propos\/partenaires-communautaires\/\" target=\"_blank\" rel=\"noopener\"><strong>Partenaires communautaires<\/strong><\/a> b\u00e9n\u00e9ficieront d&#8217;une r\u00e9duction de 500 $.<br \/>\nContactez-nous \u00e0 l&#8217;adresse <a href=\"mailto:info@prideatwork.ca\" target=\"_blank\" rel=\"noopener\">info@prideatwork.ca<\/a> et demandez votre code de partenaire.<\/li>\n<li><strong>Tarif sp\u00e9cial : 100 $ moins !<\/strong><br \/>\nAchetez votre billet avant le vendredi 13 janvier 2023 et b\u00e9n\u00e9ficiez d&#8217;une r\u00e9duction de 100 $. Il suffit d&#8217;appliquer le code <strong>SPARK_EB13<\/strong> lors de l&#8217;achat de votre billet, et il est cumulable avec la r\u00e9duction sur les billets des partenaires.<\/li>\n<\/ul>\n<p>Sur Eventbrite (page en anglais), il sera demand\u00e9 aux participant.e.s d&#8217;indiquer quelques d\u00e9tails personnels &amp; professionnels, des demandes d&#8217;accessibilit\u00e9, des restrictions alimentaires &amp; des allergies et de classer les <strong>tables rondes<\/strong> : la solidarit\u00e9 autochtone, le racisme anti-noir et l\u2019accessibilit\u00e9. Nous vous informerons bient\u00f4t des pan\u00e9listes pour chaque session.<\/p>\n<h6><a href=\"https:\/\/www.eventbrite.ca\/e\/spark-registration-480054053597?aff=GeneralPublic\" target=\"_blank\" rel=\"noopener\">ACHETEZ VOTRE BILLET ICI<\/a>.<\/h6>\n<h5 style=\"text-align: center;\">PAN\u00c9LISTES<\/h5>\n<p>[vc_row]<\/p>\n<p><strong>[vc_column width=&#8221;1\/2&#8243;]<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-220920 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/11\/CHRIS_BW.jpg\" alt=\"\" width=\"400\" height=\"400\" \/><\/p>\n<p><center><strong>Chris Bergeron (elle\/la)<br \/>\nVice-pr\u00e9sidente de la cr\u00e9ativit\u00e9 inclusive<br \/>\nCossette<br \/>\nPan\u00e9liste principale<\/strong><\/center>Pendant pr\u00e8s de 40 ans, Chris Bergeron a v\u00e9cu la vie d&#8217;un homme h\u00e9t\u00e9rosexuel. D\u00e8s le d\u00e9but de sa carri\u00e8re, elle a connu un grand succ\u00e8s professionnel : apr\u00e8s avoir \u00e9t\u00e9 collaboratrice au sein de grandes bo\u00eetes m\u00e9diatiques dont La Presse et Radio-Canada, Chris a dirig\u00e9 pendant cinq ans le journal VOIR, qui repr\u00e9sentait \u00e0 l\u2019\u00e9poque le plus grand r\u00e9seau de magazines culturels hebdomadaires au Qu\u00e9bec. Elle a ensuite fait le saut dans le monde de la publicit\u00e9 o\u00f9 elle a occup\u00e9 le poste de directrice de la cr\u00e9ation pour de grandes agences. Puis, elle est sortie du placard et a commenc\u00e9 \u00e0 vivre sa vie authentique en tant que femme trans. Le fait d\u2019\u00eatre soudainement propuls\u00e9e dans la r\u00e9alit\u00e9 d\u2019une minorit\u00e9 visible de genre a profond\u00e9ment transform\u00e9 sa perception du monde. Au Qu\u00e9bec comme \u00e0 l\u2019\u00e9tranger, Chris milite pour la diversit\u00e9, l\u2019inclusion et les droits des personnes trans en partageant son exp\u00e9rience v\u00e9cue avec le public. Elle intervient fr\u00e9quemment dans l\u2019industrie de la publicit\u00e9 pour demander une meilleure repr\u00e9sentation des minorit\u00e9s. Chez Cossette, elle dirige une \u00e9quipe multidisciplinaire de strat\u00e8ges, de gestionnaires communautaires et de cr\u00e9ateurs de contenu multiplateforme. Elle fait \u00e9galement partie du collectif de cr\u00e9ativit\u00e9 qui s\u2019efforce de repousser les limites de la branche cr\u00e9ative de l\u2019agence \u00e0 son bureau montr\u00e9alais. Gr\u00e2ce \u00e0 son regard cr\u00e9atif et strat\u00e9gique, elle amplifie le potentiel num\u00e9rique de la client\u00e8le de Cossette. Son portefeuille comprend plusieurs grandes marques, dont McDonald\u2019s du Canada, Destination Canada, l\u2019Alliance de l\u2019industrie touristique du Qu\u00e9bec, Tourisme Montr\u00e9al, Loto-Qu\u00e9bec, la SAQ, L&#8217;Or\u00e9al, la BDC, VIA Rail et Libert\u00e9.<\/p>\n<p><strong>[\/vc_column]<\/strong><\/p>\n<p><strong>[vc_column width=&#8221;1\/2&#8243;]<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-220921 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/03\/Colin-1.jpg\" alt=\"\" width=\"400\" height=\"400\" \/><\/p>\n<p><center><strong>Colin Druhan (il\/lui)<br \/>\nDirecteur g\u00e9n\u00e9ral<br \/>\nFiert\u00e9 au travail Canada<br \/>\nPan\u00e9liste<\/strong><\/center>Colin Druhan est un strat\u00e8ge d\u2019affaires qui poss\u00e8de plus de quinze ans d\u2019exp\u00e9rience de travail avec les communaut\u00e9s 2SLGBTQIA+. Il occupe le poste de directeur g\u00e9n\u00e9ral de Fiert\u00e9 au travail Canada depuis 2014. En 2021, il a \u00e9t\u00e9 \u00e9lu pr\u00e9sident du conseil d&#8217;administration de Volunteer Toronto, le plus grand centre de b\u00e9n\u00e9volat du Canada, o\u00f9 il a si\u00e9g\u00e9 en tant qu\u2019administrateur depuis 2018. Il si\u00e8ge \u00e9galement au conseil consultatif du Diversity Institute de la Ted Rogers School of Management de l\u2019 Universit\u00e9 m\u00e9tropolitaine de Toronto (anciennement l\u2019Universit\u00e9 Ryerson). En 2020, Colin a \u00e9t\u00e9 nomm\u00e9 Fellow DiverseCity par CivicAction, rejoignant ainsi un groupe diversifi\u00e9 de leaders \u00e9mergents qui sont passionn\u00e9s par le fa\u00e7onnement de leurs communaut\u00e9s dans la r\u00e9gion du Grand Toronto et Hamilton. Originaire de Cole Harbour, en Nouvelle-\u00c9cosse, Colin a obtenu un baccalaur\u00e9at en beaux-arts de l\u2019Universit\u00e9 NSCAD et a suivi des programmes de formation des cadres \u00e0 la Rotman School of Management et \u00e0 la Harvard Business School.<\/p>\n<p><strong>[\/vc_column]<\/strong><br \/>\n[\/vc_row]<\/p>\n<p>[vc_row]<\/p>\n<p>[vc_column width=&#8221;1\/3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-239151 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/01\/Kim-French-River-2022.jpg\" alt=\"Kim's headshot in traditional clothes\" width=\"200\" height=\"200\" \/><\/p>\n<p><center><strong>Kim Wheatley (elle\/la)<br \/>\nConseill\u00e8re culturelle Anishinaabe<br \/>\nRemarques<\/strong><\/center>Kim Wheatley est une grand-m\u00e8re traditionnelle anishinaabe d\u2019ascendance ojibway, potawatomi et carib\u00e9enne. Elle est membre de la Premi\u00e8re nation Shawanaga, situ\u00e9e sur les rives de la baie Georgienne, sur les territoires vis\u00e9s par le trait\u00e9 Robinson Huron, et elle appartient au clan de la Tortue. Son nom spirituel signifie \u00ab chef ou leader de la fleur de feu \u00bb et elle travaille depuis trois d\u00e9cennies aupr\u00e8s de communaut\u00e9s autochtones et non autochtones aux quatre coins du Canada.<br \/>\nEn tant que conf\u00e9renci\u00e8re prim\u00e9e depuis plus de trois d\u00e9cennies, Kim intervient \u00e0 l\u2019\u00e9chelle locale, nationale et internationale dans des livres, des magazines, \u00e0 la t\u00e9l\u00e9vision, \u00e0 la radio et dans de nombreux articles de presse. Elle est auteure, joueuse de tambour \u00e0 main, chanteuse, marcheuse sur l\u2019eau, artiste et praticienne de c\u00e9r\u00e9monies. Kim s\u2019engage \u00e0 forger de bonnes relations fond\u00e9es sur des actes de r\u00e9conciliation qui honorent le pass\u00e9, relient au pr\u00e9sent et contribuent \u00e0 l\u2019avenir.<\/p>\n<p>[\/vc_column]<\/p>\n<p>[vc_column width=&#8221;1\/3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-239151 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/03\/Dominic-Cole-Morgan-2-450x450.jpg\" alt=\"Dominic's headshot\" width=\"200\" height=\"200\" \/><\/p>\n<p><center><strong>Dominic Cole-Morgan (il\/lui)<br \/>\nPremier VP, R\u00e9mun\u00e9ration globale<br \/>\nBanque Scotia<br \/>\nRemarques<\/strong><\/center><br \/>\nApr\u00e8s avoir compl\u00e9t\u00e9 des \u00e9tudes universitaires en psychologie avec une mineure en statistiques, Dominic a fait une ma\u00eetrise en relations industrielles et gestion du personnel \u00e0 la London School of Economics. Dominic s\u2019est joint \u00e0 la National Australia Bank \u00e0 Londres dans un r\u00f4le de RH g\u00e9n\u00e9ralis\u00e9, puis est pass\u00e9 \u00e0 la Royal Bank of Scotland ou il faisait partie de l\u2019\u00e9quipe de Total Rewards.<br \/>\nApr\u00e8s trois ans chez Goldman Sachs en tant que vice-pr\u00e9sident de la r\u00e9mun\u00e9ration en Europe, Dominic est retourn\u00e9 \u00e0 la Royal Bank of Scotland et s\u2019est \u00e9tabli \u00e0 Hong Kong en tant que directeur r\u00e9gional de la r\u00e9mun\u00e9ration. Pendant qu\u2019il \u00e9tait \u00e0 Hong Kong, Dominic a aussi travaill\u00e9 chez Prudential Plc \u00e0 titre de directeur de la r\u00e9mun\u00e9ration pour la r\u00e9gion asiatique.<br \/>\nApr\u00e8s son retour au Royaume-Uni au bout de cinq ans, il s\u2019est joint \u00e0 Standard Life Plc en tant que directeur de la r\u00e9mun\u00e9ration de groupe et des politiques d\u2019emploi.<br \/>\nDominic s\u2019est joint \u00e0 la Banque Scotia le 1er ao\u00fbt 2018 en tant que premier vice-pr\u00e9sident de la r\u00e9mun\u00e9ration globale au sein de Total Rewards et est charg\u00e9 de la r\u00e9mun\u00e9ration et des avantages sociaux, de l\u2019efficacit\u00e9 de l\u2019organisation et de la diversit\u00e9, de l\u2019\u00e9quit\u00e9 et de l\u2019inclusion.<\/p>\n<p>[\/vc_column]<\/p>\n<p>[vc_column width=&#8221;1\/3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-239151 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/01\/Anna-Liza-Badaloo-scaled.jpg\" alt=\"Anna-Liza's headshot\" width=\"200\" height=\"200\" \/><\/p>\n<p><center><strong>Anna-Liza Badaloo (elle\/la)<br \/>\njournaliste, animatrice et consultante sp\u00e9cialis\u00e9e<br \/>\nAnimatrice<\/strong><\/center><br \/>\nAnna-Liza Badaloo est journaliste, animatrice et consultante sp\u00e9cialis\u00e9e dans le domaine \u00e0 but non lucratif qui travaille \u00e0 l\u2019intersection de la sant\u00e9, de l\u2019environnement et de la justice sociale. Consid\u00e9rant la JEDI (justice, \u00e9quit\u00e9, diversit\u00e9 et inclusion) dans une optique d\u2019empathie, son approche d\u00e9colonis\u00e9e et intersectionnelle aide les organisations \u00e0 renforcer leurs capacit\u00e9s en mettant en \u0153uvre des formations, des communaut\u00e9s de pratique, des campagnes de sensibilisation et des partenariats ax\u00e9s sur la JEDI. Engag\u00e9e \u00e0 amplifier des voix diverses, son travail r\u00e9v\u00e8le comment les syst\u00e8mes coloniaux, capitalistes, h\u00e9t\u00e9ronormatifs et capacitistes ont un impact disproportionn\u00e9 sur les communaut\u00e9s mal desservies. Elle anime actuellement le podcast de l\u2019Institute for Natural Medicine, The ND Will See You Now, et \u00e9crit sur la m\u00e9decine int\u00e9grative et l\u2019\u00e9quit\u00e9 en mati\u00e8re de sant\u00e9. Elle est associ\u00e9e au Sustainability Network, qui renforce les capacit\u00e9s des organismes environnementaux \u00e0 but non lucratif, et contribue r\u00e9guli\u00e8rement \u00e0 des magazines tels que QBiz, She is Wise, The Monitor et Indspiration. Consultez son <a href=\"https:\/\/linktr.ee\/annalizabadaloo\" target=\"_blank\" rel=\"noopener\">portfolio d\u2019articles<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/anna-liza-badaloo-a8a32923\/\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a> et <a href=\"https:\/\/www.instagram.com\/annalizabadaloo\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>.<\/p>\n<p>[\/vc_column]<\/p>\n<p>[\/vc_row]<\/p>\n<p><center><\/p>\n<h6>Pan\u00e9listes des tables rondes<\/h6>\n<p><\/center><\/p>\n<p>[vc_row]<\/p>\n<p>[vc_column width=&#8221;1\/3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-239151 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/01\/Tim-Geauvreau-scaled.jpg\" alt=\"Tim's headshot\" width=\"200\" height=\"200\" \/><\/p>\n<p><center><strong>Tim Geauvreau (il\/lui)<br \/>\nFinances &amp; administration<br \/>\nWorkforce Warriors<br \/>\nLa solidarit\u00e9 autochtone<\/strong><\/center><br \/>\nTim est une personne bispirituelle originaire de la Premi\u00e8re Nation Atikameksheng Anishnawbek, en Ontario. Tim se consid\u00e8re comme un v\u00e9ritable guerrier de la main-d&#8217;\u0153uvre (Workforce Warrior). Il a d\u00e9m\u00e9nag\u00e9 \u00e0 Toronto \u00e0 l&#8217;\u00e2ge de 18 ans et poss\u00e8de 10 ans d&#8217;exp\u00e9rience en gestion d&#8217;h\u00f4tellerie et de restauration, 8 ans \u00e0 la Banque de Montr\u00e9al, 10 ans \u00e0 la mise en \u0153uvre de services externalis\u00e9s de centres d&#8217;appels pour de grandes entreprises nationales, 2 ans comme gestionnaire principal des op\u00e9rations pour un organisme \u00e0 but non lucratif et 2 ans dans le domaine de l&#8217;entreposage et de la logistique. Il est \u00e9galement entrepreneur et propri\u00e9taire de <a href=\"http:\/\/www.Ts-meatshop.ca\" rel=\"noopener\" target=\"_blank\">www.Ts-meatshop.ca<\/a> avec son partenaire.<br \/>\nTim est heureux de pouvoir mettre son exp\u00e9rience au service des communaut\u00e9s et des personnes autochtones pour les aider \u00e0 avoir confiance en leur succ\u00e8s et \u00e0 partager leurs r\u00e9ussites avec d&#8217;autres en tant que mentors.<br \/>\n[\/vc_column]<\/p>\n<p>[vc_column width=&#8221;1\/3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-239151 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/01\/Hildah-Juma.jpg\" alt=\"Hildah's headshot\" width=\"200\" height=\"200\" \/><\/p>\n<p><center><strong>Hildah Juma (elle\/la)<br \/>\nDirectrice g\u00e9n\u00e9rale<br \/>\nBlack Talent Initiative<br \/>\nLe racisme anti-noir<\/strong><\/center><br \/>\nHildah Juma est la directrice g\u00e9n\u00e9rale de Black Talent Initiative. Elle dirige le d\u00e9veloppement op\u00e9rationnel de cette jeune entreprise \u00e0 impact social en assurant la planification strat\u00e9gique et en \u00e9tablissant des partenariats, des mentorats et des opportunit\u00e9s de mise en r\u00e9seau pour d\u00e9velopper et inspirer les talents noirs. Par le biais du d\u00e9veloppement communautaire, Hildah cherche \u00e0 faire cro\u00eetre le nombre de membres de l&#8217;organisation tout en cr\u00e9ant des espaces innovants pour pr\u00e9senter et apprendre des leaders et des professionnels des communaut\u00e9s noires.<br \/>\nHildah a \u00e9t\u00e9 inspir\u00e9e par le monde des organismes \u00e0 but non lucratif, plus particuli\u00e8rement par le secteur de l&#8217;\u00e9ducation postsecondaire. Elle poss\u00e8de plus de dix ans d&#8217;exp\u00e9rience et a \u00e9t\u00e9 directrice g\u00e9n\u00e9rale de la F\u00e9d\u00e9ration canadienne des \u00e9tudiantes et \u00e9tudiants-Ontario, o\u00f9 elle a fourni des strat\u00e9gies de revendication efficaces pour faire pression sur les diff\u00e9rents paliers de gouvernement dans un cadre anti-oppressif, pour plus d&#8217;un demi-million d&#8217;\u00e9tudiants coll\u00e9giaux et universitaires partout au pays.<br \/>\nHildah est titulaire d&#8217;un baccalaur\u00e9at sp\u00e9cialis\u00e9 en sciences politiques et en philosophie ainsi que d&#8217;un certificat en gestion des organismes \u00e0 but non lucratif. Elle poss\u00e8de une vaste exp\u00e9rience dans la cr\u00e9ation de r\u00e8glements administratifs et de politiques ainsi que dans l&#8217;animation de rencontres \u00e0 grand d\u00e9ploiement.<br \/>\n[\/vc_column]<\/p>\n<p>[vc_column width=&#8221;1\/3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-239151 aligncenter\" style=\"border-radius: 50%;\" src=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2023\/01\/Melissa-Egan.jpeg\" alt=\"Melissa's headshot\" width=\"200\" height=\"200\" \/><\/p>\n<p><center><strong>Melissa Egan (elle\/la)<br \/>\nChef des projets nationaux sur les Invalidit\u00e9s Episodiques<br \/>\nR\u00e9alise<br \/>\nL\u2019accessibilit\u00e9<\/strong><\/center><br \/>\nMelissa Egan est la chef des projets nationaux sur les invalidit\u00e9s \u00e9pisodiques chez Realize\/R\u00e9alise. Elle travaille dans le domaine de l&#8217;\u00e9ducation en mati\u00e8re de sant\u00e9 depuis plus de 20 ans en tant que pr\u00e9sentatrice et animatrice, et \u00e9labore et offre des formations pour divers publics partout au Canada. Melissa s&#8217;engage \u00e0 promouvoir l&#8217;inclusion, la diversit\u00e9, l&#8217;\u00e9quit\u00e9 et l&#8217;accessibilit\u00e9 dans son travail, et a travaill\u00e9 intensivement avec les communaut\u00e9s 2SLGBTQI+. Elle termine actuellement une ma\u00eetrise en \u00e9ducation et vit \u00e0 Toronto avec sa femme et leurs chats.<br \/>\n[\/vc_column]<\/p>\n<p>[\/vc_row]<\/p>\n<p><strong>Cet \u00e9v\u00e9nement payant porte sur le leadership et est ouvert \u00e0 toute personne int\u00e9ress\u00e9e. L\u2019\u00e9v\u00e9nement en anglais sera pr\u00e9sent\u00e9 en pr\u00e9sentiel et le nombre de participants est limit\u00e9.<\/strong><\/p>\n<p>Des questions sur <strong>SPARK<\/strong> ? Veuillez envoyer un courriel \u00e0 <a href=\"mailto:info@prideatwork.ca\">info@prideatwork.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Veuillez noter que cet \u00e9v\u00e9nement est offert en anglais.) Le vendredi 10 f\u00e9vrier 2023 de 8 h \u00e0 12 h HNE &#8211; Cet \u00e9v\u00e9nement payant porte sur le leadership et est ouvert \u00e0 toute personne int\u00e9ress\u00e9e. L\u2019\u00e9v\u00e9nement en anglais sera pr\u00e9sent\u00e9 en pr\u00e9sentiel et le nombre de participants est limit\u00e9. SPARK est un \u00e9v\u00e9nement cr\u00e9atif\/d&#8217;affaires d\u2019une demie-journ\u00e9e qui met en relation des leaders en mati\u00e8re de diversit\u00e9, d\u2019\u00e9quit\u00e9 et d\u2019inclusion (DEI) avec des cadres sup\u00e9rieurs [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[37,35],"class_list":["post-3925613","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-leadership-fr","tribe_events_cat-networking-fr","cat_leadership-fr","cat_networking-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SPARK - Pride At Work Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPARK - Pride At Work Canada\" \/>\n<meta property=\"og:description\" content=\"(Veuillez noter que cet \u00e9v\u00e9nement est offert en anglais.) Le vendredi 10 f\u00e9vrier 2023 de 8 h \u00e0 12 h HNE &#8211; Cet \u00e9v\u00e9nement payant porte sur le leadership et est ouvert \u00e0 toute personne int\u00e9ress\u00e9e. L\u2019\u00e9v\u00e9nement en anglais sera pr\u00e9sent\u00e9 en pr\u00e9sentiel et le nombre de participants est limit\u00e9. SPARK est un \u00e9v\u00e9nement cr\u00e9atif\/d&#8217;affaires d\u2019une demie-journ\u00e9e qui met en relation des leaders en mati\u00e8re de diversit\u00e9, d\u2019\u00e9quit\u00e9 et d\u2019inclusion (DEI) avec des cadres sup\u00e9rieurs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/\" \/>\n<meta property=\"og:site_name\" content=\"Pride At Work Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-25T20:21:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/12\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/\",\"name\":\"SPARK - Pride At Work Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg\",\"datePublished\":\"2022-12-01T14:44:29+00:00\",\"dateModified\":\"2023-01-25T20:21:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg\",\"contentUrl\":\"https:\\\/\\\/prideatwork.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/event\\\/spark-20230210\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SPARK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/\",\"name\":\"Pride At Work Canada\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prideatwork.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPARK - Pride At Work Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/","og_locale":"fr_FR","og_type":"article","og_title":"SPARK - Pride At Work Canada","og_description":"(Veuillez noter que cet \u00e9v\u00e9nement est offert en anglais.) Le vendredi 10 f\u00e9vrier 2023 de 8 h \u00e0 12 h HNE &#8211; Cet \u00e9v\u00e9nement payant porte sur le leadership et est ouvert \u00e0 toute personne int\u00e9ress\u00e9e. L\u2019\u00e9v\u00e9nement en anglais sera pr\u00e9sent\u00e9 en pr\u00e9sentiel et le nombre de participants est limit\u00e9. SPARK est un \u00e9v\u00e9nement cr\u00e9atif\/d&#8217;affaires d\u2019une demie-journ\u00e9e qui met en relation des leaders en mati\u00e8re de diversit\u00e9, d\u2019\u00e9quit\u00e9 et d\u2019inclusion (DEI) avec des cadres sup\u00e9rieurs [&hellip;]","og_url":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/","og_site_name":"Pride At Work Canada","article_modified_time":"2023-01-25T20:21:09+00:00","og_image":[{"url":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/12\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/","url":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/","name":"SPARK - Pride At Work Canada","isPartOf":{"@id":"https:\/\/prideatwork.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/#primaryimage"},"image":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/#primaryimage"},"thumbnailUrl":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/12\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg","datePublished":"2022-12-01T14:44:29+00:00","dateModified":"2023-01-25T20:21:09+00:00","breadcrumb":{"@id":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/#primaryimage","url":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/12\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg","contentUrl":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2022\/12\/PAWC_Spark_1000x500_Banner_FR_FINAL_NOLOGO.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/prideatwork.ca\/fr\/event\/spark-20230210\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prideatwork.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/prideatwork.ca\/fr\/events\/"},{"@type":"ListItem","position":3,"name":"SPARK"}]},{"@type":"WebSite","@id":"https:\/\/prideatwork.ca\/#website","url":"https:\/\/prideatwork.ca\/","name":"Pride At Work Canada","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prideatwork.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/3925613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":47,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/3925613\/revisions"}],"predecessor-version":[{"id":3952446,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/3925613\/revisions\/3952446"}],"wp:attachment":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/media?parent=3925613"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tags?post=3925613"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=3925613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}