{"id":4173641,"date":"2024-03-08T10:59:35","date_gmt":"2024-03-08T15:59:35","guid":{"rendered":"https:\/\/prideatwork.ca\/?p=4173641"},"modified":"2024-03-08T10:59:35","modified_gmt":"2024-03-08T15:59:35","slug":"leadership-femmes-queers-trans","status":"publish","type":"post","link":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/","title":{"rendered":"Le leadership des femmes queers et trans"},"content":{"rendered":"<p>[vc_section nav_skin=&#8221;light&#8221;][vc_row nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221;][vc_column css_animation=&#8221;&#8221;][vc_text_element css_animation=&#8221;&#8221;]<span style=\"font-weight: 400;\">Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab <a href=\"https:\/\/www.unwomen.org\/fr\/nouvelles\/annonce\/2023\/12\/journee-internationale-des-femmes-2024-investir-en-faveur-des-femmes-accelerer-le-rythme\" target=\"_blank\" rel=\"noopener\">Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme<\/a> \u00bb<\/span><span style=\"font-weight: 400;\">, se concentre sur le leadership, <a href=\"https:\/\/www.unwomen.org\/sites\/default\/files\/2023-07\/lgbtiq-equality-and-rights-internal-resource-guide-en.pdf\" target=\"_blank\" rel=\"noopener\">l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s<\/a> (en anglais)<\/span><span style=\"font-weight: 400;\">\u00a0pour les femmes. Depuis sa cr\u00e9ation, Fiert\u00e9 au travail Canada s\u2019engage \u00e0 cr\u00e9er et \u00e0 promouvoir des milieux de travail qui reconnaissent l\u2019ensemble des membres du personnel, ind\u00e9pendamment de leur expression de genre, de leur identit\u00e9 de genre ou de leur orientation sexuelle. Nos programmes et ressources sont con\u00e7us pour promouvoir l\u2019\u00e9quit\u00e9 des genres et aborder les questions intersectionnelles.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les femmes queers et trans font figure de pionni\u00e8res dans un monde o\u00f9 r\u00e8gnent le sexisme, l\u2019homophobie et la transmisogynie. Nous avons voulu en savoir plus sur leurs exp\u00e9riences en mati\u00e8re de leadership, tant les d\u00e9fis que les r\u00e9ussites. Notre derni\u00e8re \u00e9tude, dont les donn\u00e9es et recommandations ont \u00e9t\u00e9 publi\u00e9es dans le rapport \u00ab <a href=\"https:\/\/prideatwork.ca\/fr\/lead-with-pride\/\" target=\"_blank\" rel=\"noopener\">Diriger avec fiert\u00e9 : pratiques exemplaires pour l\u2019avancement du leadership 2SLGBTQIA+<\/a> \u00bb<\/span><span style=\"font-weight: 400;\">, s\u2019est pench\u00e9e sur le cheminement des communaut\u00e9s 2SLGBTQIA+ vers le leadership.<\/span>[\/vc_text_element][vc_image_element image=&#8221;4173631&#8243; alignment=&#8221;center&#8221; preloader=&#8221;&#8221; css_animation=&#8221;&#8221;][vc_text_element css_animation=&#8221;&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 13px;\">Carolyne De Bellefeuille, Katia Aubin (directrice du conseil d&#8217;administration), <\/span><\/strong><strong><span style=\"font-size: 13px;\">Marika Roberts<br \/>\net Martine Roy (ancienne directrice du conseil d&#8217;administration) at Fiert\u00e9 des neiges \u00e0 Montreal (2024).<\/span><\/strong><\/p>\n<p>[\/vc_text_element][vc_text_element css_animation=&#8221;&#8221;]<i><span style=\"font-weight: 400;\">Diriger avec fiert\u00e9<\/span><\/i><span style=\"font-weight: 400;\"> pr\u00e9sente une analyse des parcours professionnels et des exp\u00e9riences de leaders queers et trans, ainsi que des pratiques en milieu de travail d\u2019organismes employeurs des secteurs priv\u00e9, public et \u00e0 but non lucratif, afin de comprendre les obstacles, les soutiens et les possibilit\u00e9s qui s\u2019offrent \u00e0 la communaut\u00e9 professionnelle queer et trans pour acc\u00e9der \u00e0 des postes de direction au Canada. L\u2019\u00e9tude se penche sur ces parcours professionnels et partage les t\u00e9moignages de femmes queers et trans confront\u00e9es \u00e0 des d\u00e9fis et \u00e0 des discriminations.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Plusieurs de nos conclusions sont li\u00e9es \u00e0 un manque de leadership dans la reconnaissance des talents au sein des \u00e9quipes de travail et aux barri\u00e8res syst\u00e9miques qui entravent l\u2019avancement professionnel et les avantages sociaux inclusifs. Il existe des diff\u00e9rences significatives entre les pratiques identifi\u00e9es comme efficaces par les dirigeants et les pratiques r\u00e9ellement utilis\u00e9es par les employeurs pour faire progresser le leadership des personnes 2SLGBTQIA+. \u00ab J\u2019ai \u00e9t\u00e9 confront\u00e9e \u00e0 plus d\u2019obstacles en tant que femme dans ce secteur en raison de ma bisexualit\u00e9\u2026 [bien que] je subisse moins de microagressions \u00e0 mesure que je progresse dans ma carri\u00e8re\u2026 j\u2019ai adopt\u00e9 un style plus masculin pour me faire entendre \u00bb, a d\u00e9clar\u00e9 une femme blanche bisexuelle, interrog\u00e9e dans le cadre de l\u2019\u00e9tude.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est essentiel de revoir et d\u2019actualiser les pratiques de recrutement aux \u00e9chelons sup\u00e9rieurs et de d\u00e9velopper des voies d\u2019acc\u00e8s aux postes de direction plus riches en diversit\u00e9, tout en cr\u00e9ant une reconnaissance formelle et en confiant la responsabilit\u00e9 de ce travail aux gestionnaires, aux cadres sup\u00e9rieurs et \u00e0 la direction. D\u2019autre part, m\u00eame si elles ont \u00e9t\u00e9 victimes de marginalisation et de discrimination, les femmes participantes ont estim\u00e9 que leur identit\u00e9 et leurs exp\u00e9riences v\u00e9cues les ont aid\u00e9es \u00e0 d\u00e9velopper de solides comp\u00e9tences en mati\u00e8re de leadership, telles que l\u2019empathie, la conscience de soi, l\u2019adaptabilit\u00e9, l\u2019inclusivit\u00e9, l\u2019ing\u00e9niosit\u00e9 et le charisme, ainsi que des styles de leadership ax\u00e9s sur l\u2019authenticit\u00e9, l\u2019\u00e9tablissement de liens, la diversit\u00e9 et la confiance.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00ab J\u2019aurais aim\u00e9 avoir un\u00b7e mentor\u00b7e qui me montre comment \u00eatre un\u00b7e leader trans en situation de handicap. [Cela] aurait pu m\u2019aider dans mon d\u00e9veloppement de carri\u00e8re, d\u2019avoir une personne haut plac\u00e9e, queer, ou encore en situation de handicap, pour m\u2019aider \u00e0 naviguer dans ces espaces et relever ces d\u00e9fis \u00bb, a soulign\u00e9 une femme trans latino-am\u00e9ricaine, en situation de handicap et issue de l\u2019immigration. Voil\u00e0 pourquoi le soutien au d\u00e9veloppement et \u00e0 l\u2019avancement des membres du personnel 2SLGBTQIA+ vers des postes de direction, par le biais du mentorat, du parrainage et du d\u00e9veloppement des voies d\u2019acc\u00e8s au leadership, repr\u00e9sente une solution int\u00e9ressante pour garantir davantage d\u2019opportunit\u00e9s pour toustes, y compris pour les femmes queers et trans.<\/span>[\/vc_text_element][vc_image_element image=&#8221;4173633&#8243; alignment=&#8221;center&#8221; preloader=&#8221;&#8221; css_animation=&#8221;&#8221;][vc_text_element css_animation=&#8221;&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 13px;\">Kim Wheatley ouvre SPARK de bon c\u0153ur \u00e0 Toronto (2023).<\/span><\/strong><\/p>\n<p>[\/vc_text_element][vc_text_element css_animation=&#8221;&#8221;]<\/p>\n<h6>Initiatives collaboratives<b><\/b><\/h6>\n<p><span style=\"font-weight: 400;\">Au Canada, nous avons \u00e9galement constat\u00e9 de nombreuses avanc\u00e9es et politiques visant \u00e0 faire augmenter le nombre de femmes dans les r\u00f4les de direction et les conseils d\u2019administration et \u00e0 garantir l\u2019\u00e9galit\u00e9 des sexes et des genres. L\u2019une d\u2019entre elles a \u00e9t\u00e9 lanc\u00e9e par le gouvernement du Canada en 2020 : <\/span><a href=\"https:\/\/ised-isde.canada.ca\/site\/isde\/fr\/defi-50-30-votre-avantage-diversite\"><span style=\"font-weight: 400;\">le D\u00e9fi 50-30<\/span><\/a><span style=\"font-weight: 400;\">. Fiert\u00e9 au travail Canada a \u00e9t\u00e9 parmi les nombreuses organisations qui ont conseill\u00e9 et collabor\u00e9 \u00e0 la cr\u00e9ation de cette initiative et en est signataire, aux c\u00f4t\u00e9s de diverses organisations, institutions et r\u00e9seaux de promotion de la diversit\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019initiative s\u2019adresse aux entreprises canadiennes, aux organismes \u00e0 but non lucratif et aux \u00e9tablissements d\u2019enseignement sup\u00e9rieur, qui s\u2019engagent \u00e0 atteindre la parit\u00e9 des genres (50 %) et une repr\u00e9sentation significative (30 %) d\u2019autres groupes sous-repr\u00e9sent\u00e9s &#8211; notamment les personnes racialis\u00e9es, les personnes autochtones, les personnes en situation de handicap et les membres de la communaut\u00e9 2SLGBTQIA+ &#8211; au sein des conseils d\u2019administration et des postes de direction des entreprises.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le D\u00e9fi 50-30 et Fiert\u00e9 au travail Canada peuvent aider les organisations \u00e0 atteindre leurs objectifs gr\u00e2ce \u00e0 des strat\u00e9gies efficaces en mati\u00e8re de diversit\u00e9 et d\u2019inclusion. \u00ab Je conseille aux leaders de se d\u00e9faire de cette mentalit\u00e9 selon laquelle, par exemple, il suffit de consulter LinkedIn pour trouver une personne autochtone qui occupe un poste de vice-pr\u00e9sidence et la recruter. Ces personnes ne sont pas l\u00e0, mais elles sont pr\u00e9sentes en interne dans nos \u00e9quipes. Nous comptons des personnes qui portent ces identit\u00e9s et qui sont capables d\u2019acc\u00e9der aux \u00e9chelons sup\u00e9rieurs. Il suffit d\u2019investir en elles, de les soutenir et de les faire progresser, \u00bb a affirm\u00e9 une femme lesbienne originaire d\u2019Asie de l\u2019Est et issue de l\u2019immigration. <\/span><i><span style=\"font-weight: 400;\">(Diriger avec fiert\u00e9)<\/span><\/i><\/p>\n<p><b>Outils et ressources<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/prideatwork.ca\/fr\/lead-with-pride\/\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">Diriger avec fiert\u00e9 : pratiques exemplaires pour l\u2019avancement du leadership 2SLGBTQIA+<\/span><\/i><\/a><span style=\"font-weight: 400;\"> (2023 &#8211; anglais et fran\u00e7ais)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/prideatwork.ca\/fr\/transitioning-employers\/\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">La transition des organismes employeurs : une \u00e9tude sur les politiques et les pratiques favorisant l\u2019int\u00e9gration des personnes trans en milieu de travail<\/span><\/i><\/a><span style=\"font-weight: 400;\"> (2020 &#8211; anglais et fran\u00e7ais)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/prideatwork.ca\/fr\/event\/spark\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">SPARK<\/span><\/a><span style=\"font-weight: 400;\"> (17 avril 2024)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/prideatwork.ca\/fr\/programmes\/rendez-vous\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Rendez-Vous : discussion en ligne pour femmes 2SLGBTQIA+ et personnes non binaires<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/prideatwork.ca\/fr\/programmes\/matrices\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Matrices : r\u00e9seautage num\u00e9rique pour personnes trans, non binaires et agenres<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/prideatwork.ca\/fr\/programmes\/ressources\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Rapports, guides et bo\u00eetes \u00e0 outils<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/prideatwork.ca\/fr\/nous-rejoindre\/simpliquer\/devenir-partenaire\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Devenir Fi\u00e8re partenaire<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a style=\"letter-spacing: -0.03px;\" href=\"https:\/\/unglobalcompact.ca\/take-action\/page.php?id=31\" target=\"_blank\" rel=\"noopener\">Bo\u00eete \u00e0 outils pour favoriser l\u2019\u00e9galit\u00e9 entre les genres en milieu de travail<\/a><span style=\"font-weight: 400;\"> &#8211; R\u00e9seau Canada du Pacte mondial de l\u2019ONU (2024 &#8211; anglais et fran\u00e7ais)<\/span><\/li>\n<\/ul>\n<p>[\/vc_text_element][\/vc_column][\/vc_row][\/vc_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_section nav_skin=&#8221;light&#8221;][vc_row nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221;][vc_column css_animation=&#8221;&#8221;][vc_text_element css_animation=&#8221;&#8221;]Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme \u00bb, se concentre sur le leadership, l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s (en anglais)\u00a0pour les femmes. [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[92,91],"tags":[],"class_list":["post-4173641","post","type-post","status-publish","format-standard","hentry","category-defense-des-interets-2slgbtqia","category-journees-d-observation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le leadership des femmes queers et trans - Pride At Work Canada<\/title>\n<meta name=\"description\" content=\"Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme \u00bb, se concentre sur le leadership, l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s pour les femmes. Depuis sa cr\u00e9ation, Fiert\u00e9 au travail Canada s\u2019engage \u00e0 cr\u00e9er et \u00e0 promouvoir des milieux de travail qui reconnaissent l\u2019ensemble des membres du personnel, ind\u00e9pendamment de leur expression de genre, de leur identit\u00e9 de genre ou de leur orientation sexuelle. Nos programmes et ressources sont con\u00e7us pour promouvoir l\u2019\u00e9quit\u00e9 des genres et aborder les questions intersectionnelles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le leadership des femmes queers et trans\" \/>\n<meta property=\"og:description\" content=\"Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme \u00bb, se concentre sur le leadership, l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s pour les femmes. Depuis sa cr\u00e9ation, Fiert\u00e9 au travail Canada s\u2019engage \u00e0 cr\u00e9er et \u00e0 promouvoir des milieux de travail qui reconnaissent l\u2019ensemble des membres du personnel, ind\u00e9pendamment de leur expression de genre, de leur identit\u00e9 de genre ou de leur orientation sexuelle. Nos programmes et ressources sont con\u00e7us pour promouvoir l\u2019\u00e9quit\u00e9 des genres et aborder les questions intersectionnelles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/\" \/>\n<meta property=\"og:site_name\" content=\"Pride At Work Canada\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T15:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prideatwork.ca\/wp-content\/uploads\/2024\/03\/IWsD-2024-FR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#\\\/schema\\\/person\\\/adcd596241e08417ee4b22c9333adf69\"},\"headline\":\"Le leadership des femmes queers et trans\",\"datePublished\":\"2024-03-08T15:59:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/\"},\"wordCount\":1274,\"articleSection\":[\"D\u00e9fense des int\u00e9r\u00eats 2SLGBTQIA+\",\"Journ\u00e9es d'observation\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/\",\"name\":\"Le leadership des femmes queers et trans - Pride At Work Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\"},\"datePublished\":\"2024-03-08T15:59:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#\\\/schema\\\/person\\\/adcd596241e08417ee4b22c9333adf69\"},\"description\":\"Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme \u00bb, se concentre sur le leadership, l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s pour les femmes. Depuis sa cr\u00e9ation, Fiert\u00e9 au travail Canada s\u2019engage \u00e0 cr\u00e9er et \u00e0 promouvoir des milieux de travail qui reconnaissent l\u2019ensemble des membres du personnel, ind\u00e9pendamment de leur expression de genre, de leur identit\u00e9 de genre ou de leur orientation sexuelle. Nos programmes et ressources sont con\u00e7us pour promouvoir l\u2019\u00e9quit\u00e9 des genres et aborder les questions intersectionnelles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/leadership-femmes-queers-trans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le leadership des femmes queers et trans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#website\",\"url\":\"https:\\\/\\\/prideatwork.ca\\\/\",\"name\":\"Pride At Work Canada\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prideatwork.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prideatwork.ca\\\/#\\\/schema\\\/person\\\/adcd596241e08417ee4b22c9333adf69\",\"name\":\"editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2a3c8b4256cd1f391e28d4191ea87126e9c75bfafc2a10e6afc8c6306f57842?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2a3c8b4256cd1f391e28d4191ea87126e9c75bfafc2a10e6afc8c6306f57842?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2a3c8b4256cd1f391e28d4191ea87126e9c75bfafc2a10e6afc8c6306f57842?s=96&d=mm&r=g\",\"caption\":\"editor\"},\"url\":\"https:\\\/\\\/prideatwork.ca\\\/fr\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le leadership des femmes queers et trans - Pride At Work Canada","description":"Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme \u00bb, se concentre sur le leadership, l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s pour les femmes. Depuis sa cr\u00e9ation, Fiert\u00e9 au travail Canada s\u2019engage \u00e0 cr\u00e9er et \u00e0 promouvoir des milieux de travail qui reconnaissent l\u2019ensemble des membres du personnel, ind\u00e9pendamment de leur expression de genre, de leur identit\u00e9 de genre ou de leur orientation sexuelle. Nos programmes et ressources sont con\u00e7us pour promouvoir l\u2019\u00e9quit\u00e9 des genres et aborder les questions intersectionnelles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/","og_locale":"fr_FR","og_type":"article","og_title":"Le leadership des femmes queers et trans","og_description":"Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme \u00bb, se concentre sur le leadership, l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s pour les femmes. Depuis sa cr\u00e9ation, Fiert\u00e9 au travail Canada s\u2019engage \u00e0 cr\u00e9er et \u00e0 promouvoir des milieux de travail qui reconnaissent l\u2019ensemble des membres du personnel, ind\u00e9pendamment de leur expression de genre, de leur identit\u00e9 de genre ou de leur orientation sexuelle. Nos programmes et ressources sont con\u00e7us pour promouvoir l\u2019\u00e9quit\u00e9 des genres et aborder les questions intersectionnelles.","og_url":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/","og_site_name":"Pride At Work Canada","article_published_time":"2024-03-08T15:59:35+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/prideatwork.ca\/wp-content\/uploads\/2024\/03\/IWsD-2024-FR.png","type":"image\/png"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"editor","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/#article","isPartOf":{"@id":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/"},"author":{"name":"editor","@id":"https:\/\/prideatwork.ca\/#\/schema\/person\/adcd596241e08417ee4b22c9333adf69"},"headline":"Le leadership des femmes queers et trans","datePublished":"2024-03-08T15:59:35+00:00","mainEntityOfPage":{"@id":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/"},"wordCount":1274,"articleSection":["D\u00e9fense des int\u00e9r\u00eats 2SLGBTQIA+","Journ\u00e9es d'observation"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/","url":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/","name":"Le leadership des femmes queers et trans - Pride At Work Canada","isPartOf":{"@id":"https:\/\/prideatwork.ca\/#website"},"datePublished":"2024-03-08T15:59:35+00:00","author":{"@id":"https:\/\/prideatwork.ca\/#\/schema\/person\/adcd596241e08417ee4b22c9333adf69"},"description":"Ce n\u2019est pas d\u2019hier que les femmes s\u2019int\u00e9ressent \u00e0 l\u2019\u00e9galit\u00e9 des sexes et des genres. De nombreux mouvements f\u00e9ministes organis\u00e9s ont favoris\u00e9 la tenue de discussions visant \u00e0 faire progresser l\u2019\u00e9quit\u00e9 et l\u2019inclusion des femmes dans les processus d\u00e9cisionnels. Cette ann\u00e9e, la campagne d\u2019ONU Femmes, intitul\u00e9e \u00ab Investir en faveur des femmes : acc\u00e9l\u00e9rer le rythme \u00bb, se concentre sur le leadership, l\u2019\u00e9galit\u00e9 et les opportunit\u00e9s pour les femmes. Depuis sa cr\u00e9ation, Fiert\u00e9 au travail Canada s\u2019engage \u00e0 cr\u00e9er et \u00e0 promouvoir des milieux de travail qui reconnaissent l\u2019ensemble des membres du personnel, ind\u00e9pendamment de leur expression de genre, de leur identit\u00e9 de genre ou de leur orientation sexuelle. Nos programmes et ressources sont con\u00e7us pour promouvoir l\u2019\u00e9quit\u00e9 des genres et aborder les questions intersectionnelles.","breadcrumb":{"@id":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prideatwork.ca\/fr\/leadership-femmes-queers-trans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prideatwork.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Le leadership des femmes queers et trans"}]},{"@type":"WebSite","@id":"https:\/\/prideatwork.ca\/#website","url":"https:\/\/prideatwork.ca\/","name":"Pride At Work Canada","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prideatwork.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/prideatwork.ca\/#\/schema\/person\/adcd596241e08417ee4b22c9333adf69","name":"editor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e2a3c8b4256cd1f391e28d4191ea87126e9c75bfafc2a10e6afc8c6306f57842?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e2a3c8b4256cd1f391e28d4191ea87126e9c75bfafc2a10e6afc8c6306f57842?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2a3c8b4256cd1f391e28d4191ea87126e9c75bfafc2a10e6afc8c6306f57842?s=96&d=mm&r=g","caption":"editor"},"url":"https:\/\/prideatwork.ca\/fr\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/posts\/4173641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/comments?post=4173641"}],"version-history":[{"count":3,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/posts\/4173641\/revisions"}],"predecessor-version":[{"id":4173644,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/posts\/4173641\/revisions\/4173644"}],"wp:attachment":[{"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/media?parent=4173641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/categories?post=4173641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prideatwork.ca\/fr\/wp-json\/wp\/v2\/tags?post=4173641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}